{"id":1728,"date":"2021-06-30T19:40:02","date_gmt":"2021-06-30T19:40:02","guid":{"rendered":"https:\/\/corporativogalope.com\/?p=1728"},"modified":"2021-08-04T18:46:33","modified_gmt":"2021-08-04T18:46:33","slug":"prohibicion-de-la-subcontratacion-en-mexico","status":"publish","type":"post","link":"https:\/\/corporativogalope.com\/en\/prohibicion-de-la-subcontratacion-en-mexico\/","title":{"rendered":"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO"},"content":{"rendered":"<p>La <strong>subcontrataci\u00f3n<\/strong> llego a M\u00e9xico para solventar la necesidad de organizar la mano de obra de ciertas empresas, posteriormente, este esquema fue diversific\u00e1ndose en varios sectores sin que esto implique la eliminaci\u00f3n de derechos a los trabajadores u obligaciones de los patrones.<\/p>\n<p>Con el paso del tiempo, las diversas administraciones p\u00fablicas tuvieron que emitir leyes y reglas para su correcta regulaci\u00f3n y aplicaci\u00f3n en M\u00e9xico, incluso cumpliendo con reglas que garantizaran que en su aplicaci\u00f3n, no se estaban llevando a cabo, actividades de financiamiento al terrorismo y lavado de dinero, por lo que esto llevo al aumento de las obligaciones para las empresas prestadoras del servicio de subcontrataci\u00f3n, a efecto de generar un esquema de certidumbre en lo corresponde a su aplicaci\u00f3n jur\u00eddica.<\/p>\n<p>Bajo esta premisa, se observa que la subcontrataci\u00f3n no constituye una actividad ilegal, mucho menos il\u00edcita y en otro sentido, es la misma que solventaba las necesidades de empleo que se presentaban en el pa\u00eds, ya que, trabajaba en conjunto con los patrones en la distribuci\u00f3n de las cargas laborales, fiscales y de seguridad social. Sin embargo, pese a ser ya una actividad regulada por las leyes laborales como corresponde, estamos ahora ante un escenario que ha optado por prohibirla, considerando solo su aplicaci\u00f3n para casos excepcionales como lo es un servicio especializado, dejando en evidencia el desconocimiento de lo que realmente constituye la subcontrataci\u00f3n, su utilidad y relevancia en la generaci\u00f3n de empleos en el pa\u00eds.<\/p>\n<p>En M\u00e9xico, existe una constante inclinaci\u00f3n por parte del Estado en generar marcos normativos que se adecuen a la pol\u00edtica fiscal del partido en turno, generando as\u00ed grandes cambios a esquemas ya establecidos en administraciones pasadas, aun cuando estos cambios constitu\u00edan una revoluci\u00f3n en la esfera jur\u00eddica de los contribuyentes. Actualmente, estamos frente a una administraci\u00f3n que se ha caracterizado por ir en contra de los modelos neoliberales, libre mercado y sector empresarial, acusando incluso a las administraciones p\u00fablicas pasadas de ser c\u00f3mplices de violentar los derechos de los trabajadores en materia laboral y de seguridad social, lleg\u00e1ndolos a etiquetar como grupos criminales<\/p>\n<p>Como resultado de esta percepci\u00f3n, se empez\u00f3 a regular la subcontrataci\u00f3n desde un punto de vista de la prohibici\u00f3n, considerando la generalidad, pero no las particularidades que esta decisi\u00f3n pudiese llegar a tener en el \u00e1mbito del empleo en M\u00e9xico.<\/p>\n<p>Una de las principales quejas para llevar a la subcontrataci\u00f3n al terreno de la prohibici\u00f3n fue que este esquema operaba solo en da\u00f1o moral hac\u00eda los trabajadores, priv\u00e1ndolos de todo derecho laboral y creando escenarios de simulaci\u00f3n, teniendo como resultado un esquema de subcontrataci\u00f3n ilegal. Aunado a lo anterior, se sostiene que este esquema tiene como \u00fanica finalidad la emisi\u00f3n de comprobantes fiscales que respalden estas operaciones, denominando a estas empresas como \u201cfactureros\u201d.<\/p>\n<p>Ante esta postura por parte del Gobierno Mexicano, es necesario preguntarse: \u00bfLa legislaci\u00f3n aprobada en materia de subcontrataci\u00f3n ayudar\u00e1 a solucionar los problemas de empleo en M\u00e9xico?<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La subcontrataci\u00f3n llego a M\u00e9xico para solventar la necesidad de organizar la mano de obra de ciertas empresas, posteriormente, este esquema fue diversific\u00e1ndose en varios sectores sin que esto implique la eliminaci\u00f3n de derechos a los trabajadores u obligaciones de los patrones. Con el paso del tiempo, las diversas administraciones p\u00fablicas tuvieron que emitir leyes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1729,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[35],"tags":[],"class_list":["post-1728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO - GALOPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporativogalope.com\/en\/prohibicion-de-la-subcontratacion-en-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO - GALOPE\" \/>\n<meta property=\"og:description\" content=\"La subcontrataci\u00f3n llego a M\u00e9xico para solventar la necesidad de organizar la mano de obra de ciertas empresas, posteriormente, este esquema fue diversific\u00e1ndose en varios sectores sin que esto implique la eliminaci\u00f3n de derechos a los trabajadores u obligaciones de los patrones. Con el paso del tiempo, las diversas administraciones p\u00fablicas tuvieron que emitir leyes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporativogalope.com\/en\/prohibicion-de-la-subcontratacion-en-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"GALOPE\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-30T19:40:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T18:46:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporativogalope.com\/wp-content\/uploads\/2021\/06\/subcontratacion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#\\\/schema\\\/person\\\/aa11bc2ac8403a97efb7d44861058381\"},\"headline\":\"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO\",\"datePublished\":\"2021-06-30T19:40:02+00:00\",\"dateModified\":\"2021-08-04T18:46:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/\"},\"wordCount\":540,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporativogalope.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/subcontratacion.png\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/\",\"url\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/\",\"name\":\"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO - GALOPE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporativogalope.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/subcontratacion.png\",\"datePublished\":\"2021-06-30T19:40:02+00:00\",\"dateModified\":\"2021-08-04T18:46:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporativogalope.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/subcontratacion.png\",\"contentUrl\":\"https:\\\/\\\/corporativogalope.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/subcontratacion.png\",\"width\":517,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/prohibicion-de-la-subcontratacion-en-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/\",\"name\":\"GALOPE\",\"description\":\"CORPORATIVO GALOPE\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#organization\",\"name\":\"GALOPE\",\"url\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporativogalope.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo-con-blanco.png\",\"contentUrl\":\"https:\\\/\\\/corporativogalope.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo-con-blanco.png\",\"width\":618,\"height\":478,\"caption\":\"GALOPE\"},\"image\":{\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporativogalope.com\\\/es_es\\\/#\\\/schema\\\/person\\\/aa11bc2ac8403a97efb7d44861058381\",\"name\":\"editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1b181c1aba4d2d02509578967543fad49884913890fd72974c914b5526add63?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1b181c1aba4d2d02509578967543fad49884913890fd72974c914b5526add63?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1b181c1aba4d2d02509578967543fad49884913890fd72974c914b5526add63?s=96&d=mm&r=g\",\"caption\":\"editor\"},\"url\":\"https:\\\/\\\/corporativogalope.com\\\/en\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO - GALOPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporativogalope.com\/en\/prohibicion-de-la-subcontratacion-en-mexico\/","og_locale":"en_US","og_type":"article","og_title":"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO - GALOPE","og_description":"La subcontrataci\u00f3n llego a M\u00e9xico para solventar la necesidad de organizar la mano de obra de ciertas empresas, posteriormente, este esquema fue diversific\u00e1ndose en varios sectores sin que esto implique la eliminaci\u00f3n de derechos a los trabajadores u obligaciones de los patrones. Con el paso del tiempo, las diversas administraciones p\u00fablicas tuvieron que emitir leyes [&hellip;]","og_url":"https:\/\/corporativogalope.com\/en\/prohibicion-de-la-subcontratacion-en-mexico\/","og_site_name":"GALOPE","article_published_time":"2021-06-30T19:40:02+00:00","article_modified_time":"2021-08-04T18:46:33+00:00","og_image":[{"width":517,"height":500,"url":"https:\/\/corporativogalope.com\/wp-content\/uploads\/2021\/06\/subcontratacion.png","type":"image\/png"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"editor","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#article","isPartOf":{"@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/"},"author":{"name":"editor","@id":"https:\/\/corporativogalope.com\/es_es\/#\/schema\/person\/aa11bc2ac8403a97efb7d44861058381"},"headline":"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO","datePublished":"2021-06-30T19:40:02+00:00","dateModified":"2021-08-04T18:46:33+00:00","mainEntityOfPage":{"@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/"},"wordCount":540,"commentCount":0,"publisher":{"@id":"https:\/\/corporativogalope.com\/es_es\/#organization"},"image":{"@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/corporativogalope.com\/wp-content\/uploads\/2021\/06\/subcontratacion.png","articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/","url":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/","name":"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO - GALOPE","isPartOf":{"@id":"https:\/\/corporativogalope.com\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#primaryimage"},"image":{"@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/corporativogalope.com\/wp-content\/uploads\/2021\/06\/subcontratacion.png","datePublished":"2021-06-30T19:40:02+00:00","dateModified":"2021-08-04T18:46:33+00:00","breadcrumb":{"@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#primaryimage","url":"https:\/\/corporativogalope.com\/wp-content\/uploads\/2021\/06\/subcontratacion.png","contentUrl":"https:\/\/corporativogalope.com\/wp-content\/uploads\/2021\/06\/subcontratacion.png","width":517,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/corporativogalope.com\/es_es\/prohibicion-de-la-subcontratacion-en-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/corporativogalope.com\/es_es\/"},{"@type":"ListItem","position":2,"name":"PROHIBICI\u00d3N DE LA SUBCONTRATACI\u00d3N EN M\u00c9XICO"}]},{"@type":"WebSite","@id":"https:\/\/corporativogalope.com\/es_es\/#website","url":"https:\/\/corporativogalope.com\/es_es\/","name":"GALOPE","description":"CORPORATIVO GALOPE","publisher":{"@id":"https:\/\/corporativogalope.com\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporativogalope.com\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/corporativogalope.com\/es_es\/#organization","name":"GALOPE","url":"https:\/\/corporativogalope.com\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/corporativogalope.com\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/corporativogalope.com\/wp-content\/uploads\/2020\/11\/logo-con-blanco.png","contentUrl":"https:\/\/corporativogalope.com\/wp-content\/uploads\/2020\/11\/logo-con-blanco.png","width":618,"height":478,"caption":"GALOPE"},"image":{"@id":"https:\/\/corporativogalope.com\/es_es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/corporativogalope.com\/es_es\/#\/schema\/person\/aa11bc2ac8403a97efb7d44861058381","name":"editor","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f1b181c1aba4d2d02509578967543fad49884913890fd72974c914b5526add63?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1b181c1aba4d2d02509578967543fad49884913890fd72974c914b5526add63?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1b181c1aba4d2d02509578967543fad49884913890fd72974c914b5526add63?s=96&d=mm&r=g","caption":"editor"},"url":"https:\/\/corporativogalope.com\/en\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/posts\/1728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/comments?post=1728"}],"version-history":[{"count":2,"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/posts\/1728\/revisions"}],"predecessor-version":[{"id":1791,"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/posts\/1728\/revisions\/1791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/media\/1729"}],"wp:attachment":[{"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/media?parent=1728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/categories?post=1728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporativogalope.com\/en\/wp-json\/wp\/v2\/tags?post=1728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}